{"id":15862,"date":"2023-10-03T16:31:09","date_gmt":"2023-10-03T14:31:09","guid":{"rendered":"http:\/\/www.gebirgsverein-services.at\/gruppen\/?p=15862"},"modified":"2023-10-03T16:31:09","modified_gmt":"2023-10-03T14:31:09","slug":"skiwoche-mittersill-2024","status":"publish","type":"post","link":"https:\/\/www.gebirgsverein-services.at\/gruppen\/2023\/10\/03\/skiwoche-mittersill-2024\/","title":{"rendered":"Skiwoche Mittersill 2024"},"content":{"rendered":"<p>Schiwoche in den Kitzb\u00fchler Alpen<br \/>\nTermin : <strong>Samstag 20.01.2024 bis Samstag 27.01.2024<\/strong><\/p>\n<p>1 Woche Schilauf im alpinen Gel\u00e4nde der Kitzb\u00fcheler Alpen.<br \/>\nDem laut Top oft The Mountains besten Skigebiet der Welt.<br \/>\nDie Betreuung erfolgt durch erfahrene Schilehrer des OEAV.<\/p>\n<p>Gleichzeitig wird eine Gruppe mit einem Schitourenf\u00fchrer unter der Ben\u00fctzung<br \/>\nder Lifte im alpinen Gel\u00e4nde gef\u00fchrt. ( Je nach Wetterlage )<\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-4038 alignleft lazyload\" data-src=\"http:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2013\/09\/bergbahn-kitzbuehel.png\" alt=\"\" width=\"194\" height=\"194\" data-srcset=\"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2013\/09\/bergbahn-kitzbuehel.png 194w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2013\/09\/bergbahn-kitzbuehel-150x150.png 150w\" data-sizes=\"(max-width: 194px) 100vw, 194px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 194px; --smush-placeholder-aspect-ratio: 194\/194;\" \/><\/strong><strong>Unterbringung:<\/strong> <a href=\"http:\/\/www.braurup.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hotel Br\u00e4urup<\/a> &#8211; ausgestattet mit Bad oder Dusche, WC, Haarf\u00f6n, Minibar, Radio, Telefon ,Kabel TV und Zimmersafe.\u00a0<span style=\"color: #000000; line-height: 1.3em;\">Inklusive Sauna und Dampfbad. Vital-Fr\u00fchst\u00fccksbuffet, *Gratis Skijause am Nachmittag*, abends ein Salatbuffet, ein 4-Gang Men\u00fc oder Buffetabend. Einmalig: H\u00fcttenabend mit Livemusik.<\/span><\/p>\n<p><strong>Kosten:<\/strong> 999,00 \u20ac pro Person (davon 615\u20ac Hotel und 384\u20ac f\u00fcr Lift, Skilehrer und Organisation)<\/p>\n<p><strong>Leistung:\u00a0<\/strong>7 Tage Halbpension im Doppelzimmer (EZ-Zuschlag 10\u20ac\/Tag), 6 Tages Skipass f\u00fcr die Kitzb\u00fcheler Alpen<\/p>\n<p><span style=\"color: #000000;\"><strong>Kursleitung und Anmeldung: <\/strong>Erich Litzlbauer, Tel. 0676 400 3206<br \/>\nDie Anzahlung von EUR 150,00 wird nicht r\u00fcckerstattet.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schiwoche in den Kitzb\u00fchler Alpen Termin : Samstag 20.01.2024 bis Samstag 27.01.2024 1 Woche Schilauf im alpinen Gel\u00e4nde der Kitzb\u00fcheler Alpen. Dem laut Top oft The Mountains besten Skigebiet der Welt. Die Betreuung erfolgt durch erfahrene Schilehrer des OEAV. Gleichzeitig wird eine Gruppe mit einem Schitourenf\u00fchrer unter der Ben\u00fctzung der Lifte im alpinen Gel\u00e4nde gef\u00fchrt. [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-15862","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-allgemein","7":"czr-hentry"},"acf":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/posts\/15862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/comments?post=15862"}],"version-history":[{"count":0,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/posts\/15862\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/media?parent=15862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/categories?post=15862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/tags?post=15862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}