{"id":11427,"date":"2021-07-02T08:15:59","date_gmt":"2021-07-02T06:15:59","guid":{"rendered":"http:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434.jpg"},"modified":"2021-07-02T08:16:18","modified_gmt":"2021-07-02T06:16:18","slug":"img_1434","status":"inherit","type":"attachment","link":"https:\/\/www.gebirgsverein-services.at\/gruppen\/gloggnitz\/img_1434\/","title":{"rendered":"IMG_1434"},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"class_list":["post-11427","attachment","type-attachment","status-inherit","czr-hentry"],"acf":[],"smush":{"stats":{"percent":6.903324157120445,"bytes":139929,"size_before":2026980,"size_after":1887051,"time":1.2900000000000003,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":8.26,"bytes":1747,"size_before":21156,"size_after":19409,"time":0.06},"large":{"percent":6.96,"bytes":12916,"size_before":185669,"size_after":172753,"time":0.21},"thumbnail":{"percent":8.49,"bytes":836,"size_before":9842,"size_after":9006,"time":0.01},"medium_large":{"percent":7.24,"bytes":8201,"size_before":113253,"size_after":105052,"time":0.06},"1536x1536":{"percent":6.42,"bytes":23268,"size_before":362412,"size_after":339144,"time":0.11},"tc-masonry-thumb-size":{"percent":7.42,"bytes":5019,"size_before":67672,"size_after":62653,"time":0.09},"tc-masonry-bi-thumb-size":{"percent":6.82,"bytes":10007,"size_before":146630,"size_after":136623,"time":0.19},"tc-grid-full":{"percent":6.96,"bytes":10789,"size_before":154999,"size_after":144210,"time":0.11},"tc-grid":{"percent":7.57,"bytes":5450,"size_before":71987,"size_after":66537,"time":0.03},"tc-thumb":{"percent":7.86,"bytes":2103,"size_before":26752,"size_after":24649,"time":0.06},"slider-full":{"percent":7.07,"bytes":18390,"size_before":260194,"size_after":241804,"time":0.07},"slider":{"percent":6.91,"bytes":12021,"size_before":174036,"size_after":162015,"time":0.06},"tc-sq-thumb":{"percent":7.38,"bytes":6584,"size_before":89261,"size_after":82677,"time":0.02},"tc-ws-thumb":{"percent":6.82,"bytes":14556,"size_before":213506,"size_after":198950,"time":0.12},"tc-ws-small-thumb":{"percent":7.62,"bytes":4437,"size_before":58258,"size_after":53821,"time":0.03},"tc-slider-small":{"percent":7.72,"bytes":3605,"size_before":46704,"size_after":43099,"time":0.04},"fpc-size":{"percent":0,"bytes":0,"size_before":24649,"size_after":24649,"time":0.02}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" data-src=\"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-300x169.jpg\" class=\"attachment-medium size-medium no-lazy lazyload\" alt=\"\" data-srcset=\"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-300x169.jpg 300w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1024x576.jpg 1024w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-768x432.jpg 768w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1536x864.jpg 1536w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-570x321.jpg 570w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1110x624.jpg 1110w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-528x297.jpg 528w, https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434.jpg 1600w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/169;\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Windw\u00fcrfe werden aufgearbeitet<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":900,"file":"2021\/07\/IMG_1434.jpg","sizes":{"medium":{"file":"IMG_1434-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-300x169.jpg"},"large":{"file":"IMG_1434-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1024x576.jpg"},"thumbnail":{"file":"IMG_1434-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-150x150.jpg"},"medium_large":{"file":"IMG_1434-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-768x432.jpg"},"1536x1536":{"file":"IMG_1434-1536x864.jpg","width":1536,"height":864,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1536x864.jpg"},"tc-masonry-thumb-size":{"file":"IMG_1434-570x321.jpg","width":570,"height":321,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-570x321.jpg"},"tc-masonry-bi-thumb-size":{"file":"IMG_1434-570x869.jpg","width":570,"height":869,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-570x869.jpg"},"tc-grid-full":{"file":"IMG_1434-1110x444.jpg","width":1110,"height":444,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1110x444.jpg"},"tc-grid":{"file":"IMG_1434-570x350.jpg","width":570,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-570x350.jpg"},"tc-thumb":{"file":"IMG_1434-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-270x250.jpg"},"slider-full":{"file":"IMG_1434-1600x500.jpg","width":1600,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1600x500.jpg"},"slider":{"file":"IMG_1434-1110x500.jpg","width":1110,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1110x500.jpg"},"tc-sq-thumb":{"file":"IMG_1434-510x510.jpg","width":510,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-510x510.jpg"},"tc-ws-thumb":{"file":"IMG_1434-1110x624.jpg","width":1110,"height":624,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-1110x624.jpg"},"tc-ws-small-thumb":{"file":"IMG_1434-528x297.jpg","width":528,"height":297,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-528x297.jpg"},"tc-slider-small":{"file":"IMG_1434-517x235.jpg","width":517,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-517x235.jpg"},"fpc-size":{"file":"IMG_1434-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434-270x250.jpg"},"full":{"file":"IMG_1434.jpg","width":1600,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434.jpg"}},"image_meta":{"aperture":"3.2","credit":"Picasa","camera":"Canon IXUS 185","caption":"","created_timestamp":"1623495859","copyright":"","focal_length":"5","iso":"400","shutter_speed":"0.002","title":"","orientation":"0","keywords":[]}},"post":154,"source_url":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-content\/uploads\/2021\/07\/IMG_1434.jpg","_links":{"self":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/media\/11427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/comments?post=11427"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":154,"href":"https:\/\/www.gebirgsverein-services.at\/gruppen\/wp-json\/wp\/v2\/pages\/154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}